{"id":984,"date":"2018-03-14T14:33:36","date_gmt":"2018-03-14T14:33:36","guid":{"rendered":"http:\/\/www.mecamaster.com\/mm\/?page_id=984"},"modified":"2022-11-21T08:59:46","modified_gmt":"2022-11-21T08:59:46","slug":"mecamaster-assembly-tolerances-3d","status":"publish","type":"page","link":"http:\/\/www.mecamaster.com\/mm\/fr\/produits-services\/mecamaster-assembly-tolerances-3d\/","title":{"rendered":"MECAmaster Assembly (Tol\u00e9rances 3D)"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"984\" class=\"elementor elementor-984\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8455753 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8455753\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c6529a\" data-id=\"6c6529a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b63344b elementor-widget elementor-widget-text-editor\" data-id=\"b63344b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h3>MECAmaster Assembly est une solution puissante et robuste pour l\u2019analyse des variations 3D dans un assemblage avec identification des causes respectives.<\/h3>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e466a3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e466a3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a634c68\" data-id=\"a634c68\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f78b361 elementor-widget elementor-widget-text-editor\" data-id=\"f78b361\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>MECAmaster offre la possibilit\u00e9 de simuler et d\u2019analyser sur des exigences g\u00e9om\u00e9triques l\u2019impact final des choix de conception et des tol\u00e9rances d\u2019entr\u00e9e attendues sur les composants.<\/p><p>Bas\u00e9 sur un mod\u00e8le num\u00e9rique, MECAmaster n\u00e9cessite des informations tr\u00e8s \u00e9l\u00e9mentaires pour travailler et est alors tr\u00e8s bien adapt\u00e9 depuis la conception pr\u00e9liminaire.<br \/> Donner la possibilit\u00e9 aux concepteurs le plus t\u00f4t possible de faire l\u2019exp\u00e9rience des cons\u00e9quences g\u00e9om\u00e9triques des concepts \u00e0 l\u2019\u00e9tude permettra de penser la conception avec robustesse et avec une optique qualit\u00e9 g\u00e9om\u00e9trique finale.<\/p><p>MECAmaster Assembly permet entre autres de :<\/p><ul><li>exp\u00e9rimenter \u00e0 partir d\u2019une conception pr\u00e9liminaire la robustesse de l\u2019architecture d\u2019assemblage \u2026<\/li><li>calculer les chaines de cotes 3D et aider \u00e0 d\u00e9finir les tol\u00e9rances dimensionnelles et g\u00e9om\u00e9triques des composants \u2026<\/li><li>simuler statistiquement des assemblages virtuels pour estimer les taux de non-conformit\u00e9, etc \u2026<\/li><li>Simuler num\u00e9riquement l\u2019impact des valeurs mesur\u00e9es r\u00e9elles avant la r\u00e9alisation de l\u2019assemblage\u00a0 \u2026<\/li><\/ul><p>Ces informations (Variation 3D, influences de l\u2019architecture, tol\u00e9rances, \u2026 ) permettent aujourd\u2019hui \u00e0 de nombreuses entreprises de travailler sur une conception robuste.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b3ec81f\" data-id=\"b3ec81f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-caa5ecd elementor-widget elementor-widget-image\" data-id=\"caa5ecd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"605\" src=\"http:\/\/www.mecamaster.com\/mm\/wp-content\/uploads\/2018\/03\/MCA3DEXP_CONCEPT-1024x605.png\" class=\"attachment-large size-large wp-image-764\" alt=\"\" srcset=\"http:\/\/www.mecamaster.com\/mm\/wp-content\/uploads\/2018\/03\/MCA3DEXP_CONCEPT-1024x605.png 1024w, http:\/\/www.mecamaster.com\/mm\/wp-content\/uploads\/2018\/03\/MCA3DEXP_CONCEPT-300x177.png 300w, http:\/\/www.mecamaster.com\/mm\/wp-content\/uploads\/2018\/03\/MCA3DEXP_CONCEPT-768x454.png 768w, http:\/\/www.mecamaster.com\/mm\/wp-content\/uploads\/2018\/03\/MCA3DEXP_CONCEPT.png 1827w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e79fc0 elementor-widget elementor-widget-image\" data-id=\"5e79fc0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"605\" src=\"http:\/\/www.mecamaster.com\/mm\/wp-content\/uploads\/2018\/03\/MCAV5_TURBO_MC-1024x605.bmp\" class=\"attachment-large size-large wp-image-987\" alt=\"\" srcset=\"http:\/\/www.mecamaster.com\/mm\/wp-content\/uploads\/2018\/03\/MCAV5_TURBO_MC-1024x605.bmp 1024w, http:\/\/www.mecamaster.com\/mm\/wp-content\/uploads\/2018\/03\/MCAV5_TURBO_MC-300x177.bmp 300w, http:\/\/www.mecamaster.com\/mm\/wp-content\/uploads\/2018\/03\/MCAV5_TURBO_MC-768x454.bmp 768w, http:\/\/www.mecamaster.com\/mm\/wp-content\/uploads\/2018\/03\/MCAV5_TURBO_MC.bmp 1827w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b3f66fa elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b3f66fa\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6a07c89\" data-id=\"6a07c89\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d97165 elementor-widget elementor-widget-html\" data-id=\"0d97165\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div style=\"display: none;\" class=\"crellyslider-slider crellyslider-slider-full-width crellyslider-slider-3dtol_slider_fr crellyslider-4\" id=\"crellyslider-4\">\n<ul>\n<li\nstyle=\"\nbackground-color: transparent;\nbackground-image: none;\nbackground-position: center center;\nbackground-repeat: repeat;\nbackground-size: cover;\n\n\"\ndata-in=\"fade\"\ndata-ease-in=\"300\"\ndata-out=\"fade\"\ndata-ease-out=\"300\"\ndata-time=\"6000\"\n>\n<img\nclass=\"\"\nsrc=\"http:\/\/www.mecamaster.com\/mm\/wp-content\/uploads\/2018\/03\/MCA3DExp_PREDIM_w500.png\"\nalt=\"\"\nstyle=\"\nz-index: 1;\n\n\"\ndata-delay=\"0\"\ndata-ease-in=\"300\"\ndata-ease-out=\"300\"\ndata-in=\"slideLeft\"\ndata-out=\"slideLeft\"\ndata-ignore-ease-out=\"0\"\ndata-top=\"52\"\ndata-left=\"0\"\ndata-time=\"all\"\n\/>\n<div\nclass=\"\"\nstyle=\"z-index: 1;\nfont-family: Roboto;\n\n\"\ndata-delay=\"0\"\ndata-ease-in=\"300\"\ndata-ease-out=\"300\"\ndata-in=\"slideLeft\"\ndata-out=\"fadeLeft\"\ndata-ignore-ease-out=\"0\"\ndata-top=\"20\"\ndata-left=\"528\"\ndata-time=\"all\"\n><span style=\"font-size: 40px;\"><b>Analyse concept \/ Architecture<\/b><\/span><br \/><br \/><span style=\"font-size: 25px; color: #000000;\"><strong>Objectifs\u00a0<\/strong><\/span><br \/><span style=\"font-size: 18px; color: #000000;\">- Comparer les concepts d'asemblage \/ configurations d'un design<br \/>\u00a0 pr\u00e9liminaire<\/span><br \/><span style=\"font-size: 18px; color: #000000;\">- D\u00e9cliner les exigences d'un niveau assemblage au niveau sous-<br \/><\/span><span style=\"font-size: 18px;\">\u00a0 ensemble.<\/span><br \/><br \/><span style=\"font-size: 25px; color: #000000;\"><strong>Comment MECAmaster intervient ?<\/strong><\/span><br \/><span style=\"font-size: 18px;\">Gr\u00e2ce \u00e0 une d\u00e9finition d'interfaces m\u00e9caniques facile et une analyse\u00a0<br \/>de sensibilit\u00e9, MECAmaster\u00a0donne d'importantes informations\u00a0sur la <br \/>robustesse g\u00e9om\u00e9trique du concept d'assemblage.<\/span><\/div>\n<\/li>\n<li\nstyle=\"\nbackground-color: transparent;\nbackground-image: none;\nbackground-position: center center;\nbackground-repeat: repeat;\nbackground-size: cover;\n\n\"\ndata-in=\"fade\"\ndata-ease-in=\"300\"\ndata-out=\"fade\"\ndata-ease-out=\"300\"\ndata-time=\"3000\"\n>\n<img\nclass=\"\"\nsrc=\"http:\/\/www.mecamaster.com\/mm\/wp-content\/uploads\/2018\/03\/MCA3DExp_CONCEPT2_w500.png\"\nalt=\"\"\nstyle=\"\nz-index: 1;\n\n\"\ndata-delay=\"0\"\ndata-ease-in=\"300\"\ndata-ease-out=\"300\"\ndata-in=\"slideLeft\"\ndata-out=\"slideLeft\"\ndata-ignore-ease-out=\"0\"\ndata-top=\"52\"\ndata-left=\"0\"\ndata-time=\"all\"\n\/>\n<div\nclass=\"\"\nstyle=\"z-index: 1;\nfont-family: Roboto;\n\n\"\ndata-delay=\"0\"\ndata-ease-in=\"300\"\ndata-ease-out=\"300\"\ndata-in=\"slideLeft\"\ndata-out=\"slideLeft\"\ndata-ignore-ease-out=\"0\"\ndata-top=\"23\"\ndata-left=\"528\"\ndata-time=\"all\"\n><span style=\"font-size: 40px; color: #000000;\"><strong>Conception D\u00e9taill\u00e9e<\/strong><\/span><br \/><br \/><span style=\"font-size: 25px; color: #000000;\"><strong>Objectifs :\u00a0<\/strong><\/span><br \/><span style=\"font-size: 18px;\"><span style=\"color: #000000;\">- Calcul des chaines de cotes 3D en prenant en compte les principes<br \/>\u00a0 constructifs de l'assemblage et v\u00e9rifier la faisabilit\u00e9 des exigences<\/span><\/span><br \/><span style=\"font-size: 18px; color: #000000;\">- Identifier les contributeurs majoritaires pour ajuster les Tolerances <br \/>\u00a0 Dimensionnelles et g\u00e9om\u00e9triques\u00a0<\/span><br \/><br \/><span style=\"font-size: 25px; color: #000000;\"><strong>Comment MECAmaster intervient ?<\/strong><\/span><br \/><span style=\"font-size: 18px;\">MECAmaster calcule les d\u00e9placements r\u00e9sultants en utilisant un <br \/>calcul robuste, num\u00e9rique, qui prend en compte les principes constructifs<br \/>de l'assemblage et des tol\u00e9rances pr\u00e9visionnelles d\u00e9finies .<\/span><\/div>\n<\/li>\n<li\nstyle=\"\nbackground-color: transparent;\nbackground-image: none;\nbackground-position: center center;\nbackground-repeat: repeat;\nbackground-size: cover;\n\n\"\ndata-in=\"fade\"\ndata-ease-in=\"300\"\ndata-out=\"fade\"\ndata-ease-out=\"300\"\ndata-time=\"3000\"\n>\n<img\nclass=\"\"\nsrc=\"http:\/\/www.mecamaster.com\/mm\/wp-content\/uploads\/2018\/03\/MCA3DEXP_STAT_w500.png\"\nalt=\"\"\nstyle=\"\nz-index: 1;\n\n\"\ndata-delay=\"0\"\ndata-ease-in=\"300\"\ndata-ease-out=\"300\"\ndata-in=\"slideLeft\"\ndata-out=\"slideLeft\"\ndata-ignore-ease-out=\"0\"\ndata-top=\"56\"\ndata-left=\"0\"\ndata-time=\"all\"\n\/>\n<div\nclass=\"\"\nstyle=\"z-index: 1;\nfont-family: Roboto;\n\n\"\ndata-delay=\"0\"\ndata-ease-in=\"300\"\ndata-ease-out=\"300\"\ndata-in=\"fade\"\ndata-out=\"fade\"\ndata-ignore-ease-out=\"0\"\ndata-top=\"10\"\ndata-left=\"528\"\ndata-time=\"all\"\n><span style=\"font-size: 40px; color: #000000;\"><strong>Validation Statistique<\/strong><\/span><br \/><br \/><span style=\"font-size: 25px; color: #000000;\"><strong>Objectifs :\u00a0<\/strong><\/span><br \/><span style=\"font-size: 18px;\">Simuler des assemblages virtuels en int\u00e9grant des informations <br \/>statistiques \u00e9l\u00e9mentaires sur les tol\u00e9rances d'entr\u00e9e et estimation <br \/>de non-conforme pr\u00e9visionnel ...\u00a0<\/span><br \/><br \/><span style=\"font-size: 25px; color: #000000;\"><strong>Comment MECAmaster intervient ?<br \/><\/strong><\/span><span style=\"font-size: 18px;\">MECAmaster construira un tr\u00e8s grand nombre d'assemblages virtuels<br \/>\u00a0en tenant compte des informations statistiques fournies sur les <br \/>valeurs d'entr\u00e9e pour obtenir une population compl\u00e8te de r\u00e9sultats <br \/>dans un temps\u00a0de calcul tr\u00e9s rapide, et en extraire des informations <br \/>statistiques.<\/span><\/div>\n<\/li>\n<li\nstyle=\"\nbackground-color: transparent;\nbackground-image: none;\nbackground-position: center center;\nbackground-repeat: repeat;\nbackground-size: cover;\n\n\"\ndata-in=\"fade\"\ndata-ease-in=\"300\"\ndata-out=\"fade\"\ndata-ease-out=\"300\"\ndata-time=\"3000\"\n>\n<img\nclass=\"\"\nsrc=\"http:\/\/www.mecamaster.com\/mm\/wp-content\/uploads\/2018\/03\/MCA_MAP_w500.png\"\nalt=\"\"\nstyle=\"\nz-index: 1;\n\n\"\ndata-delay=\"0\"\ndata-ease-in=\"300\"\ndata-ease-out=\"300\"\ndata-in=\"slideLeft\"\ndata-out=\"slideLeft\"\ndata-ignore-ease-out=\"0\"\ndata-top=\"53\"\ndata-left=\"0\"\ndata-time=\"all\"\n\/>\n<div\nclass=\"\"\nstyle=\"z-index: 1;\nfont-family: Roboto;\n\n\"\ndata-delay=\"0\"\ndata-ease-in=\"300\"\ndata-ease-out=\"300\"\ndata-in=\"slideLeft\"\ndata-out=\"fadeLeft\"\ndata-ignore-ease-out=\"0\"\ndata-top=\"10\"\ndata-left=\"528\"\ndata-time=\"all\"\n><span style=\"font-size: 40px;\"><b>Int\u00e9gration de valeurs r\u00e9elles<\/b><\/span><br \/><br \/><span style=\"font-size: 25px; color: #000000;\"><strong>Objectifs<\/strong><\/span><br \/><span style=\"font-size: 18px;\">Construire un seul assemblage virtuel \u00e0 partir de valeurs <br \/>mesur\u00e9es au lieu des tol\u00e9rance pr\u00e9visionnelles pour anticiper <br \/>les r\u00e9glages n\u00e9cessaires.<\/span><br \/><br \/><span style=\"font-size: 25px; color: #000000;\"><strong>Comment MECAmaster intervient ?<\/strong><\/span><br \/><span style=\"font-size: 18px;\">MECAmaster offre la possibilit\u00e9 d'int\u00e9grer sur chaque\u00a0<br \/>interface m\u00e9canique des valeurs mesur\u00e9es sign\u00e9es au lieu\u00a0<br \/>d'une tol\u00e9rance pr\u00e9visionnelle. Le calcul est ensuite bas\u00e9<br \/>sur le m\u00eame mod\u00e8le mais cette fois retournant un d\u00e9placement\u00a0<br \/>et non plus une dispersion pr\u00e9visionnelle.<\/span><\/div>\n<\/li>\n<\/ul>\n<\/div>\n<script type=\"text\/javascript\">\n(function($) {\n$(document).ready(function() {\n$(\"#crellyslider-4\").crellySlider({\nlayout: 'full-width',\nresponsive: 1,\nstartWidth: 1140,\nstartHeight: 400,\nautomaticSlide: 1,\nshowControls: 1,\nshowNavigation: 1,\nenableSwipe: 1,\nshowProgressBar: 0,\npauseOnHover: 1,\nrandomOrder: 0,\nstartFromSlide: 0,\nbeforeStart : function() {},\nbeforeSetResponsive : function() {},\nbeforeSlideStart : function() {},\nbeforePause\t: function() {},\nbeforeResume : function() {},\n});\n});\n})(jQuery);\n<\/script>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-11facc4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"11facc4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b843e73\" data-id=\"b843e73\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1bc5293 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"1bc5293\" data-element_type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2911\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2911\" aria-expanded=\"false\">El\u00e9ments cl\u00e9s<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2911\" aria-expanded=\"false\">El\u00e9ments cl\u00e9s<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2911\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2911\" tabindex=\"0\" hidden=\"false\"><ul><li>Optimal d\u00e9s la conception pr\u00e9liminaire avec l\u2019anayse de solution<\/li><li>Des calculs totalement transparents et justifi\u00e9s<\/li><li>Vitesse de calcul tr\u00e9s \u00e9lev\u00e9e m\u00eame sur de tr\u00e8s grands assemblages<\/li><li>Pire cas r\u00e9el et pas un extr\u00e9mum de simulation<\/li><li>Evolution cin\u00e9matique sur les r\u00e9sultats<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-01bfcc2 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"01bfcc2\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fb7350b\" data-id=\"fb7350b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31c1aa4 elementor-widget elementor-widget-toggle\" data-id=\"31c1aa4\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-5211\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-5211\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"elementor-toggle-icon-closed fa fa-caret-right\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"elementor-toggle-icon-opened fa fa-caret-up\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Dans quels environnements MECAmaster est disponible ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-5211\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-5211\"><p>MECAmaster est aujourd\u2019hui disponible dans CATIA V5 et dans 3DEXPERIENCE.\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-5212\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-5212\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"elementor-toggle-icon-closed fa fa-caret-right\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"elementor-toggle-icon-opened fa fa-caret-up\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> Qui dois-je contacter pour une d\u00e9monstration en direct?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-5212\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-5212\"><p>Comme tout autre produit MECAmaster, vous pouvez nous contacter directement pour toute question relative \u00e0 Model Builder, merci d\u2019utiliser le formulaire de contact de ce site.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>MECAmaster Assembly est une solution puissante et robuste pour l\u2019analyse des variations 3D dans un assemblage avec identification des causes respectives. MECAmaster offre la possibilit\u00e9 de simuler et d\u2019analyser sur des exigences g\u00e9om\u00e9triques l\u2019impact final des choix de conception et des tol\u00e9rances d\u2019entr\u00e9e attendues sur les composants. Bas\u00e9 sur un mod\u00e8le num\u00e9rique, MECAmaster n\u00e9cessite des [&hellip;]<\/p>\n<div class=\"ccfw-readmore\"><a href=\"http:\/\/www.mecamaster.com\/mm\/fr\/produits-services\/mecamaster-assembly-tolerances-3d\/\" class=\"more-link\">Read More<\/a><\/div>","protected":false},"author":2,"featured_media":0,"parent":990,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"page-full-width.php","meta":{"footnotes":""},"class_list":["post-984","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MECAmaster Assembly (Tol\u00e9rances 3D) - MECAmaster<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.mecamaster.com\/mm\/fr\/produits-services\/mecamaster-assembly-tolerances-3d\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MECAmaster Assembly (Tol\u00e9rances 3D) - MECAmaster\" \/>\n<meta property=\"og:description\" content=\"MECAmaster Assembly est une solution puissante et robuste pour l\u2019analyse des variations 3D dans un assemblage avec identification des causes respectives. MECAmaster offre la possibilit\u00e9 de simuler et d\u2019analyser sur des exigences g\u00e9om\u00e9triques l\u2019impact final des choix de conception et des tol\u00e9rances d\u2019entr\u00e9e attendues sur les composants. Bas\u00e9 sur un mod\u00e8le num\u00e9rique, MECAmaster n\u00e9cessite des [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.mecamaster.com\/mm\/fr\/produits-services\/mecamaster-assembly-tolerances-3d\/\" \/>\n<meta property=\"og:site_name\" content=\"MECAmaster\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-21T08:59:46+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.mecamaster.com\/mm\/wp-content\/uploads\/2018\/03\/MCA3DEXP_CONCEPT-1024x605.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.mecamaster.com\/mm\/fr\/produits-services\/mecamaster-assembly-tolerances-3d\/\",\"url\":\"http:\/\/www.mecamaster.com\/mm\/fr\/produits-services\/mecamaster-assembly-tolerances-3d\/\",\"name\":\"MECAmaster Assembly (Tol\u00e9rances 3D) - MECAmaster\",\"isPartOf\":{\"@id\":\"http:\/\/www.mecamaster.com\/mm\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.mecamaster.com\/mm\/fr\/produits-services\/mecamaster-assembly-tolerances-3d\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/www.mecamaster.com\/mm\/fr\/produits-services\/mecamaster-assembly-tolerances-3d\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.mecamaster.com\/mm\/wp-content\/uploads\/2018\/03\/MCA3DEXP_CONCEPT-1024x605.png\",\"datePublished\":\"2018-03-14T14:33:36+00:00\",\"dateModified\":\"2022-11-21T08:59:46+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/www.mecamaster.com\/mm\/fr\/produits-services\/mecamaster-assembly-tolerances-3d\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.mecamaster.com\/mm\/fr\/produits-services\/mecamaster-assembly-tolerances-3d\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"http:\/\/www.mecamaster.com\/mm\/fr\/produits-services\/mecamaster-assembly-tolerances-3d\/#primaryimage\",\"url\":\"http:\/\/www.mecamaster.com\/mm\/wp-content\/uploads\/2018\/03\/MCA3DEXP_CONCEPT.png\",\"contentUrl\":\"http:\/\/www.mecamaster.com\/mm\/wp-content\/uploads\/2018\/03\/MCA3DEXP_CONCEPT.png\",\"width\":1827,\"height\":1079},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.mecamaster.com\/mm\/fr\/produits-services\/mecamaster-assembly-tolerances-3d\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.mecamaster.com\/mm\/en\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits &#038; Services\",\"item\":\"https:\/\/www.mecamaster.com\/mm\/fr\/produits-services\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MECAmaster Assembly (Tol\u00e9rances 3D)\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.mecamaster.com\/mm\/#website\",\"url\":\"http:\/\/www.mecamaster.com\/mm\/\",\"name\":\"MECAmaster\",\"description\":\"3D Tolerances &amp; Loads\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.mecamaster.com\/mm\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MECAmaster Assembly (Tol\u00e9rances 3D) - MECAmaster","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.mecamaster.com\/mm\/fr\/produits-services\/mecamaster-assembly-tolerances-3d\/","og_locale":"en_GB","og_type":"article","og_title":"MECAmaster Assembly (Tol\u00e9rances 3D) - MECAmaster","og_description":"MECAmaster Assembly est une solution puissante et robuste pour l\u2019analyse des variations 3D dans un assemblage avec identification des causes respectives. MECAmaster offre la possibilit\u00e9 de simuler et d\u2019analyser sur des exigences g\u00e9om\u00e9triques l\u2019impact final des choix de conception et des tol\u00e9rances d\u2019entr\u00e9e attendues sur les composants. Bas\u00e9 sur un mod\u00e8le num\u00e9rique, MECAmaster n\u00e9cessite des [&hellip;]","og_url":"http:\/\/www.mecamaster.com\/mm\/fr\/produits-services\/mecamaster-assembly-tolerances-3d\/","og_site_name":"MECAmaster","article_modified_time":"2022-11-21T08:59:46+00:00","og_image":[{"url":"http:\/\/www.mecamaster.com\/mm\/wp-content\/uploads\/2018\/03\/MCA3DEXP_CONCEPT-1024x605.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.mecamaster.com\/mm\/fr\/produits-services\/mecamaster-assembly-tolerances-3d\/","url":"http:\/\/www.mecamaster.com\/mm\/fr\/produits-services\/mecamaster-assembly-tolerances-3d\/","name":"MECAmaster Assembly (Tol\u00e9rances 3D) - MECAmaster","isPartOf":{"@id":"http:\/\/www.mecamaster.com\/mm\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.mecamaster.com\/mm\/fr\/produits-services\/mecamaster-assembly-tolerances-3d\/#primaryimage"},"image":{"@id":"http:\/\/www.mecamaster.com\/mm\/fr\/produits-services\/mecamaster-assembly-tolerances-3d\/#primaryimage"},"thumbnailUrl":"http:\/\/www.mecamaster.com\/mm\/wp-content\/uploads\/2018\/03\/MCA3DEXP_CONCEPT-1024x605.png","datePublished":"2018-03-14T14:33:36+00:00","dateModified":"2022-11-21T08:59:46+00:00","breadcrumb":{"@id":"http:\/\/www.mecamaster.com\/mm\/fr\/produits-services\/mecamaster-assembly-tolerances-3d\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.mecamaster.com\/mm\/fr\/produits-services\/mecamaster-assembly-tolerances-3d\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"http:\/\/www.mecamaster.com\/mm\/fr\/produits-services\/mecamaster-assembly-tolerances-3d\/#primaryimage","url":"http:\/\/www.mecamaster.com\/mm\/wp-content\/uploads\/2018\/03\/MCA3DEXP_CONCEPT.png","contentUrl":"http:\/\/www.mecamaster.com\/mm\/wp-content\/uploads\/2018\/03\/MCA3DEXP_CONCEPT.png","width":1827,"height":1079},{"@type":"BreadcrumbList","@id":"http:\/\/www.mecamaster.com\/mm\/fr\/produits-services\/mecamaster-assembly-tolerances-3d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mecamaster.com\/mm\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Produits &#038; Services","item":"https:\/\/www.mecamaster.com\/mm\/fr\/produits-services\/"},{"@type":"ListItem","position":3,"name":"MECAmaster Assembly (Tol\u00e9rances 3D)"}]},{"@type":"WebSite","@id":"http:\/\/www.mecamaster.com\/mm\/#website","url":"http:\/\/www.mecamaster.com\/mm\/","name":"MECAmaster","description":"3D Tolerances &amp; Loads","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.mecamaster.com\/mm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"http:\/\/www.mecamaster.com\/mm\/wp-json\/wp\/v2\/pages\/984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.mecamaster.com\/mm\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.mecamaster.com\/mm\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.mecamaster.com\/mm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.mecamaster.com\/mm\/wp-json\/wp\/v2\/comments?post=984"}],"version-history":[{"count":4,"href":"http:\/\/www.mecamaster.com\/mm\/wp-json\/wp\/v2\/pages\/984\/revisions"}],"predecessor-version":[{"id":1175,"href":"http:\/\/www.mecamaster.com\/mm\/wp-json\/wp\/v2\/pages\/984\/revisions\/1175"}],"up":[{"embeddable":true,"href":"http:\/\/www.mecamaster.com\/mm\/wp-json\/wp\/v2\/pages\/990"}],"wp:attachment":[{"href":"http:\/\/www.mecamaster.com\/mm\/wp-json\/wp\/v2\/media?parent=984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}